{"id":3867,"date":"2023-03-18T08:43:16","date_gmt":"2023-03-18T07:43:16","guid":{"rendered":"https:\/\/belfiore-italia.com\/accommodation\/mimosa\/"},"modified":"2025-09-24T13:14:13","modified_gmt":"2025-09-24T11:14:13","slug":"mimosa","status":"publish","type":"mphb_room_type","link":"https:\/\/belfiore-italia.com\/de\/accommodation\/mimosa\/","title":{"rendered":"Mimosa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3867\" class=\"elementor elementor-3867 elementor-491\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-562aec7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"562aec7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3681f62\" data-id=\"3681f62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d7595e elementor-widget elementor-widget-spacer\" data-id=\"6d7595e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62240a88 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"62240a88\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b083580\" data-id=\"5b083580\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53453c53 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"53453c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:12,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-605x465.jpg\" alt=\"Digital StillCamera\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa41-1024x768-1-605x465.jpg\" alt=\"Digital StillCamera\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa51-1024x768-1-605x465.jpg\" alt=\"Digital StillCamera\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa996x747-605x465.jpg\" alt=\"Digital StillCamera\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10852f50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10852f50\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50f321ed\" data-id=\"50f321ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40443fe elementor-widget elementor-widget-menu-anchor\" data-id=\"40443fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"more\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3124a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3124a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3371ab8\" data-id=\"3371ab8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dd48bd elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"1dd48bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__title\">Popular<\/div>\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE934;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE934;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE934;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE934;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE934;<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\">Bewertet mit 5 von 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c2c668 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"6c2c668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper \">\n                            <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                        Mimosa                    <\/h3>\n                                        <p class=\"elementor-icon-box-description\"><\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3bb45 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"5f3bb45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper \">\n                            <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                                            <\/h3>\n                                        <p class=\"elementor-icon-box-description\">Gro\u00dfz\u00fcgiges Studio mit Doppelbett, Essecke und K\u00fcchenzeile. Badezimmer mit Dusche, WC und Bidet. Eigener Sitzplatz im gro\u00dfen Garten. \n32 m\u00b2\n<\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77ce1c8 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"77ce1c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper \">\n                            <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                                            <\/h3>\n                                        <p class=\"elementor-icon-box-description\">Hauptsaison: \u20ac750 pro Woche (Samstag bis Samstag) Nebensaison: \u20ac86 pro Nacht (mind.3 N\u00e4chte)\n\nEndreinigungsgeb\u00fchr: \u20ac50 \nWeitere Einzelheiten finden Sie in unseren <a href=\"https:\/\/belfiore-italia.com\/de\/bedingungen\/\">Bedingungen<\/a>.<\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3f25c elementor-widget elementor-widget-spacer\" data-id=\"ce3f25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-98172c4\" data-id=\"98172c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cb9b89 elementor-widget elementor-widget-spacer\" data-id=\"1cb9b89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692453d elementor-widget elementor-widget-image\" data-id=\"692453d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2.jpg\" class=\"attachment-large size-large wp-image-498\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2.jpg 1024w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-300x225.jpg 300w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-768x576.jpg 768w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-107x80.jpg 107w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-394x296.jpg 394w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-915x686.jpg 915w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-133x100.jpg 133w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4755bd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4755bd6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5be115f\" data-id=\"5be115f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d3fbe4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3fbe4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b28fda7\" data-id=\"b28fda7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-330136a elementor-widget elementor-widget-shortcode\" data-id=\"330136a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"mphb_sc_availability_calendar-wrapper\">\t<div class=\"mphb-calendar mphb-datepick inlinePicker mphb-calendar--direct-booking\" data-room-type-id=\"3867\" data-monthstoshow=\"2\" data-is_show_prices=\"0\" data-is_truncate_prices=\"1\" data-is_show_prices_currency=\"0\" data-first_available_check_in_date=\"2026-07-15\"><\/div>\n\t<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8a8f79d\" data-id=\"8a8f79d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd3a8a2 elementor-widget elementor-widget-spacer\" data-id=\"cd3a8a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f7ee45 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"6f7ee45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper \">\n                            <div class=\"elementor-icon-box-content\">\n                    <h2 class=\"elementor-icon-box-title\">\n                        Verf\u00fcgbarkeit pr\u00fcfen                    <\/h2>\n                                        <p class=\"elementor-icon-box-description\">W\u00e4hlen Sie Ihre Buchungsdaten aus<\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c68c37 elementor-widget elementor-widget-shortcode\" data-id=\"1c68c37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"mphb_sc_booking_form-wrapper \">\t<form method=\"POST\" action=\"https:\/\/belfiore-italia.com\/de\/buchungsbestaetigung\/\" class=\"mphb-booking-form mphb-booking-form--direct-booking\" id=\"booking-form-3867\" data-first_available_check_in_date=\"2026-07-15\">\n\n\t\t<p class=\"mphb-required-fields-tip\"><small>Erforderliche Felder werden gefolgt von <abbr title=\"required\">*<\/abbr><\/small><\/p>\n\t\t\t\t<input type=\"hidden\" name=\"mphb_room_type_id\" value=\"3867\" \/>\n\t\t<p class=\"mphb-check-in-date-wrapper\">\n\t\t\t<label for=\"mphb_check_in_date-6a577ddcd41d5\">\n\t\t\t\tAnreisedatum\t\t\t\t<abbr title=\"Formatiert als dd\/mm\/yyyy\">*<\/abbr>\n\t\t\t<\/label>\n\t\t\t<br \/>\n\t\t\t<input id=\"mphb_check_in_date-6a577ddcd41d5\" type=\"text\" class=\"mphb-datepick\" value=\"\" required=\"required\" autocomplete=\"off\" placeholder=\"Anreisedatum\" inputmode=\"none\" \/>\n\t\t\t<input id=\"mphb_check_in_date-6a577ddcd41d5-hidden\" type=\"hidden\" name=\"mphb_check_in_date\" value=\"\" \/>\n\t\t<\/p>\n\t\t<p class=\"mphb-check-out-date-wrapper\">\n\t\t\t<label for=\"mphb_check_out_date-6a577ddcd41d5\">\n\t\t\t\tAbreisedatum\t\t\t\t<abbr title=\"Formatiert als dd\/mm\/yyyy\">*<\/abbr>\n\t\t\t<\/label>\n\t\t\t<br \/>\n\t\t\t<input id=\"mphb_check_out_date-6a577ddcd41d5\" type=\"text\" class=\"mphb-datepick\" value=\"\" required=\"required\" autocomplete=\"off\" placeholder=\"Abreisedatum\" inputmode=\"none\" \/>\n\t\t\t<input id=\"mphb_check_out_date-6a577ddcd41d5-hidden\" type=\"hidden\" name=\"mphb_check_out_date\" value=\"\" \/>\n\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"mphb-reserve-room-section mphb-hide\">\n\t\t\t\t<p class=\"mphb-rooms-quantity-wrapper mphb-rooms-quantity-multiple mphb-hide\">\n\t\t\t\t<select class=\"mphb-rooms-quantity\" id=\"mphb-rooms-quantity-3867\" name=\"mphb_rooms_details[3867]\"><option value=\"1\" selected=\"selected\">1<\/option><\/select> of <span class=\"mphb-available-rooms-count\">1<\/span> verf\u00fcgbare Unterk\u00fcnfte reservieren.\t\t\t\t<\/p>\n\t\t\t\t<p class=\"mphb-rooms-quantity-wrapper mphb-rooms-quantity-single mphb-hide\">\n\t\t\t\t\tMimosa ist f\u00fcr ausgew\u00e4hlte Daten verf\u00fcgbar.\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"mphb_is_direct_booking\" value=\"1\" \/>\n\t\t\t\t<input class=\"button mphb-button mphb-confirm-reservation\" type=\"submit\" value=\"Reservierung best\u00e4tigen\" \/>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"mphb-errors-wrapper mphb-hide\"><\/div>\n\t\t<p class=\"mphb-reserve-btn-wrapper\">\n\t\t\t<input class=\"mphb-reserve-btn button\" type=\"submit\" value=\"Verf\u00fcgbarkeit pr\u00fcfen\" \/>\n\t\t<\/p>\n\t<\/form>\n\t<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f95244d elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"f95244d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8ac283b\" data-id=\"8ac283b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ef1a793 thmv-inner-container thmv-inner-right elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef1a793\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e1564f0 thmv-flex-right\" data-id=\"e1564f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d25bf3b elementor-widget elementor-widget-image\" data-id=\"d25bf3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1170\" height=\"1451\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool.jpg\" class=\"attachment-full size-full wp-image-1079\" alt=\"Swimming pool in Le Marche, Italy\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool.jpg 1170w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-242x300.jpg 242w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-826x1024.jpg 826w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-768x952.jpg 768w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-65x80.jpg 65w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-244x303.jpg 244w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-564x700.jpg 564w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-766x950.jpg 766w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-871x1080.jpg 871w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/pool-81x100.jpg 81w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-05029e6\" data-id=\"05029e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cfadf23 thmv-inner-container thmv-inner-left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfadf23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5cbf63\" data-id=\"d5cbf63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70497ed elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"70497ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper th-show-icon\">\n                            <div class=\"elementor-icon-box-icon th-icon-size-sm\">\n                    <span class=\"elementor-icon \">\n                        <i aria-hidden=\"true\" class=\"fas fa-hands-wash\"><\/i>                    <\/span>\n                <\/div>\n                                <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                        Bettw\u00e4sche                     <\/h3>\n                                        <p class=\"elementor-icon-box-description\">Frische Bettw\u00e4sche und Handt\u00fccher werden bereitgestellt und einmal pro Woche gewechselt. Die Nutzung unserer Waschmaschine ist kostenlos. <\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c31530c\" data-id=\"c31530c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18400d5 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"18400d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper th-show-icon\">\n                            <div class=\"elementor-icon-box-icon th-icon-size-sm\">\n                    <span class=\"elementor-icon \">\n                        <i aria-hidden=\"true\" class=\"fas fa-egg\"><\/i>                    <\/span>\n                <\/div>\n                                <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                        Fr\u00fchst\u00fcck                     <\/h3>\n                                        <p class=\"elementor-icon-box-description\">In der Nebensaison bieten wir auf Anfrage Fr\u00fchst\u00fcck an\n<\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f5be2c5 thmv-inner-container thmv-inner-left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5be2c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a45d469\" data-id=\"a45d469\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f5e827 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"6f5e827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper th-show-icon\">\n                            <div class=\"elementor-icon-box-icon th-icon-size-sm\">\n                    <span class=\"elementor-icon \">\n                        <i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>                    <\/span>\n                <\/div>\n                                <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                        Curious?                    <\/h3>\n                                        <p class=\"elementor-icon-box-description\">Folgen Sie uns auf Social Media<\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4946bd0 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"4946bd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-143b4f9\" href=\"https:\/\/www.facebook.com\/525995467458539\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-6cfc594\" href=\"https:\/\/www.instagram.com\/borgo_belfiore\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-48cd862\" href=\"https:\/\/twitter.com\/borgobelfiore\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3eb9fe3\" data-id=\"3eb9fe3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e54385 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"5e54385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper th-show-icon\">\n                            <div class=\"elementor-icon-box-icon th-icon-size-sm\">\n                    <span class=\"elementor-icon \">\n                        <i aria-hidden=\"true\" class=\"fas fa-wine-glass-alt\"><\/i>                    <\/span>\n                <\/div>\n                                <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                        Aperitivo and Cena                    <\/h3>\n                                        <p class=\"elementor-icon-box-description\">Samstags laden wir unsere G\u00e4ste in der Hochsaison zu einem Begr\u00fc\u00dfungsaperitif ein. Einmal pro Woche kochen wir ein typisch italienisches Cena, ein 4-G\u00e4nge-Men\u00fc mit lokalen Produkten.  <\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3012bcc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3012bcc6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6416f5d3\" data-id=\"6416f5d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e8cb49e elementor-widget elementor-widget-menu-anchor\" data-id=\"6e8cb49e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"rooms\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c675b92 elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"2c675b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper \">\n                            <div class=\"elementor-icon-box-content\">\n                    <h3 class=\"elementor-icon-box-title\">\n                        Vielleicht gef\u00e4llt Ihnen auch...                    <\/h3>\n                                        <p class=\"elementor-icon-box-description\">Borgo Belfiore ist ein kleines Paradies f\u00fcr alle Altersgruppen. Kinder lieben den Raum, die \u00c4lteren lieben die Umgebung. Privatsph\u00e4re in Ihrer eigenen Wohnung, geselliges Beisammensein auf der Piazza oder R\u00fcckzug in den Garten. Jeder kann seinen Aufenthalt so genie\u00dfen, wie er es f\u00fcr richtig h\u00e4lt.   <\/p>\n\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67760d7 elementor-widget elementor-widget-themo-accommodation-listing\" data-id=\"67760d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-accommodation-listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-row thmv-style-4\">\n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/lavanda7-1024x683-1-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-529\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/lavanda7-1024x683-1-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/lavanda7-1024x683-1-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/lavanda\/\">\n                                                                            Lavanda                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 4<\/div>\n                                                                                                                        <p class=\"thmv-description\">Wohnzimmer mit offener K\u00fcche und guter Schlafcouch f\u00fcr zwei Personen. Schlafzimmer mit Doppelbett. \u00dcberdeckter Sitzplatz.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/lavanda\/\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/ginestra3-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-555\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/ginestra3-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/ginestra3-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Ginestra\">\n                                                                            Ginestra                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 4<\/div>\n                                                                                                                        <p class=\"thmv-description\">Gro\u00dfe Wohnk\u00fcche. Zwei Doppelzimmer. Flur mit antikem Wandschrank.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Ginestra\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/papavero2e4web-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-571\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/papavero2e4web-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/papavero2e4web-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Papavero\">\n                                                                            Papavero                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 4<\/div>\n                                                                                                                        <p class=\"thmv-description\">Gro\u00dfe Wohnk\u00fcche mit Essecke und sehr guter Schlafcouch, offene gro\u00dfe Galerie mit 2 Einzelbetten.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Papavero\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2021\/10\/anemone1-1024x683-2-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-393\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2021\/10\/anemone1-1024x683-2-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2021\/10\/anemone1-1024x683-2-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/anomone\/\">\n                                                                            Anemone                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 2<\/div>\n                                                                                                                        <p class=\"thmv-description\">Studio mit Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Eigene Sitzgruppe im gro\u00dfen Garten.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/anomone\/\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/melograno3-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-589\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/melograno3-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/melograno3-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Melograno\">\n                                                                            Melograno                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 4<\/div>\n                                                                                                                        <p class=\"thmv-description\">Wohn-\/Esszimmer mit K\u00fcchenzeile und sehr guter Schlafcouch f\u00fcr zwei Personen. Schlafzimmer mit Doppelbett. Eigene m\u00f6blierte Terrasse direkt vor dem Apartment.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Melograno\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/rosa8-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-616\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/rosa8-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/rosa8-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Rosa\">\n                                                                            Rosa                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 6<\/div>\n                                                                                                                        <p class=\"thmv-description\">Luxusapartment auf der ersten Etage neben der historischen Hauskapelle. <\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Rosa\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/iris8-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-642\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/iris8-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/iris8-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Iris\">\n                                                                            Iris                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 6<\/div>\n                                                                                                                        <p class=\"thmv-description\">Gro\u00dfz\u00fcgiger Wohn-\/Essraum mit guter Schlafcouch f\u00fcr 2 Personen und offener K\u00fcche mit Sp\u00fclmaschine, 2 Doppelzimmer.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Iris\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/oleandro2o-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-674\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/oleandro2o-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/oleandro2o-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Oleandro\">\n                                                                            Oleandro                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 6<\/div>\n                                                                                                                        <p class=\"thmv-description\">Gro\u00dfe Wohnk\u00fcche mit Sp\u00fclmaschine. Wohnzimmer mit einmaliger Aussicht und zwei einzelnen Schlafsofas. Zwei Doppelzimmer.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Oleandro\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/primula6-1024x683-1-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-409\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/primula6-1024x683-1-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/primula6-1024x683-1-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Primula\">\n                                                                            Primula                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 2<\/div>\n                                                                                                                        <p class=\"thmv-description\">Split-level Apartment. Wohnk\u00fcche mit einfacher Schlafcouch f\u00fcr eine Person. Offene Treppe zum Schlafzimmer und Badezimmer.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Primula\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/gelsomino5-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-688\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/gelsomino5-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/gelsomino5-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Gelsomino\">\n                                                                            Gelsomino                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 6<\/div>\n                                                                                                                        <p class=\"thmv-description\">Gro\u00dfz\u00fcgiger Wohnraum mit offener K\u00fcche mit Sp\u00fclmaschine und gro\u00dfer romantischer Nische mit romantischem Doppelbett. \n2 Schlafzimmer, 2 Badezimmer.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Gelsomino\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/girasole1-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-723\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/girasole1-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/girasole1-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Girasole\">\n                                                                            Girasole                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 6<\/div>\n                                                                                                                        <p class=\"thmv-description\">Gro\u00dfer Wohn-\/Essraum mit offener K\u00fcche mit Sp\u00fclmaschine und guter Schlafcouch f\u00fcr zwei Personen. Treppe zur gro\u00dfen Galerie mit 2 Betten. Schlafzimmer mit Doppelbett.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Girasole\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/malva1-1024x683-1-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-466\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/malva1-1024x683-1-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/malva1-1024x683-1-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Malva\">\n                                                                            Malva                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 2<\/div>\n                                                                                                                        <p class=\"thmv-description\">Studio mit Essecke, K\u00fcchenzeile und Doppelbett. Eigene Terrasse direkt vor dem Apartment mit sch\u00f6ner Aussicht.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Malva\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            \n\n            \n            \n\n            <div class=\"thmv-column elementor-column thmv-column-33 thmv-column-tablet-50\">\n                <div class=\"elementor-widget-wrap\">\n                                        <div class=\"thmv-grid  elementor-element\">\n                        <div class=\"thmv-grid-img\">\n                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"465\" src=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-605x465.jpg\" class=\"attachment-th_img_md_landscape size-th_img_md_landscape wp-image-496\" alt=\"\" srcset=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-605x465.jpg 605w, https:\/\/belfiore-italia.com\/wp-content\/uploads\/2023\/03\/mimosa21-1024x768-2-394x303.jpg 394w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>                                        \n                            \n                              \n\n                            \n                                \n                                                                             \n                        <\/div>\n\n                                    <div class=\"thmv-info\">\n\n                                                                                                    <h3  class=\"thmv-title\">\n                                                                        <a href=\"\/de\/accommodation\/Mimosa\">\n                                                                            Mimosa                                                                        <\/a>\n                                     \n                                <\/h3 >\n                                                            \n                                \n                                                                    <div class=\"thmv-preface\">Betten 2<\/div>\n                                                                                                                        <p class=\"thmv-description\">Ger\u00e4umiges Studio mit Doppelbett, Essecke und K\u00fcchenzeile. Private Terrasse im Hauptgarten.<\/p>\n                            \n                                                           \n\n                            <div class=\"\">\n                                                <div>\n                                        <a class=\"thmv-btn btn btn-1 th-btn btn-standard-primary streched-mobile\" href=\"\/de\/accommodation\/Mimosa\">\n                Mehr lesen                                                                                    <\/a>\n                                    <\/div>\n                                             \n                            <\/div>\n                                \n                                    <\/div>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n\n            <\/div>\n\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Studio mit Doppelbett, Wohn-\/E\u00dfecke und K\u00fcchenzeile. Eigener Sitzplatz im gro\u00dfen Garten. <\/p>\n","protected":false},"featured_media":494,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","mphb_room_type_category":[71,67,69],"mphb_room_type_tag":[],"mphb_room_type_facility":[],"class_list":["post-3867","mphb_room_type","type-mphb_room_type","status-publish","format-standard","has-post-thumbnail","hentry","mphb_room_type_category-betten-2","mphb_room_type_category-en-suite-de","mphb_room_type_category-leuchtend","mphb-room-type-adults-2","mphb-room-type-children-2",""],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Borgo Belfiore - Family vacation in Le Marche\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Anemone - Borgo Belfiore\" \/>\n\t\t<meta property=\"og:description\" content=\"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"85\" \/>\n\t\t<meta property=\"og:image:height\" content=\"80\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-16T15:33:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-11T22:07:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/525995467458539\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@borgobelfiore\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Anemone - Borgo Belfiore\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/#listItem\",\"name\":\"Unterkunftsarten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/#listItem\",\"position\":2,\"name\":\"Unterkunftsarten\",\"item\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation-category\\\/en-suite-de\\\/#listItem\",\"name\":\"En suite\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation-category\\\/en-suite-de\\\/#listItem\",\"position\":3,\"name\":\"En suite\",\"item\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation-category\\\/en-suite-de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/mimosa\\\/#listItem\",\"name\":\"Mimosa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/#listItem\",\"name\":\"Unterkunftsarten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/mimosa\\\/#listItem\",\"position\":4,\"name\":\"Mimosa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation-category\\\/en-suite-de\\\/#listItem\",\"name\":\"En suite\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#organization\",\"name\":\"Borgo Belfiore\",\"description\":\"Family vacation in Le Marche\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/\",\"telephone\":\"+393484627974\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_belfioriO1-2.jpg\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#organizationLogo\",\"width\":85,\"height\":80,\"caption\":\"Agriturismo Borgo Belfiore logo\"},\"image\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/525995467458539\",\"https:\\\/\\\/twitter.com\\\/borgobelfiore\",\"https:\\\/\\\/www.instagram.com\\\/borgo_belfiore\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#webpage\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/\",\"name\":\"Anemone - Borgo Belfiore\",\"description\":\"Gro\\u00dfz\\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\\\/Essecke und K\\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/anemone1-1024x683-2.jpg\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#mainImage\",\"width\":1024,\"height\":683},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/accommodation\\\/anemone\\\/#mainImage\"},\"datePublished\":\"2023-03-16T16:33:02+01:00\",\"dateModified\":\"2026-07-12T00:07:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/\",\"name\":\"Borgo Belfiore\",\"description\":\"Family vacation in Le Marche\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Anemone - Borgo Belfiore","description":"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.","canonical_url":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/belfiore-italia.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/#listItem","name":"Unterkunftsarten"}},{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/#listItem","position":2,"name":"Unterkunftsarten","item":"https:\/\/belfiore-italia.com\/de\/accommodation\/","nextItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation-category\/en-suite-de\/#listItem","name":"En suite"},"previousItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation-category\/en-suite-de\/#listItem","position":3,"name":"En suite","item":"https:\/\/belfiore-italia.com\/de\/accommodation-category\/en-suite-de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/mimosa\/#listItem","name":"Mimosa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/#listItem","name":"Unterkunftsarten"}},{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/mimosa\/#listItem","position":4,"name":"Mimosa","previousItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/accommodation-category\/en-suite-de\/#listItem","name":"En suite"}}]},{"@type":"Organization","@id":"https:\/\/belfiore-italia.com\/de\/#organization","name":"Borgo Belfiore","description":"Family vacation in Le Marche","url":"https:\/\/belfiore-italia.com\/de\/","telephone":"+393484627974","logo":{"@type":"ImageObject","url":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#organizationLogo","width":85,"height":80,"caption":"Agriturismo Borgo Belfiore logo"},"image":{"@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/525995467458539","https:\/\/twitter.com\/borgobelfiore","https:\/\/www.instagram.com\/borgo_belfiore\/"]},{"@type":"WebPage","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#webpage","url":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/","name":"Anemone - Borgo Belfiore","description":"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/belfiore-italia.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2021\/10\/anemone1-1024x683-2.jpg","@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#mainImage","width":1024,"height":683},"primaryImageOfPage":{"@id":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/#mainImage"},"datePublished":"2023-03-16T16:33:02+01:00","dateModified":"2026-07-12T00:07:39+02:00"},{"@type":"WebSite","@id":"https:\/\/belfiore-italia.com\/de\/#website","url":"https:\/\/belfiore-italia.com\/de\/","name":"Borgo Belfiore","description":"Family vacation in Le Marche","inLanguage":"de-DE","publisher":{"@id":"https:\/\/belfiore-italia.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Borgo Belfiore - Family vacation in Le Marche","og:type":"article","og:title":"Anemone - Borgo Belfiore","og:description":"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.","og:url":"https:\/\/belfiore-italia.com\/de\/accommodation\/anemone\/","og:image":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg","og:image:secure_url":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg","og:image:width":85,"og:image:height":80,"article:published_time":"2023-03-16T15:33:02+00:00","article:modified_time":"2026-07-11T22:07:39+00:00","article:publisher":"https:\/\/www.facebook.com\/525995467458539","twitter:card":"summary_large_image","twitter:site":"@borgobelfiore","twitter:title":"Anemone - Borgo Belfiore","twitter:description":"Gro\u00dfz\u00fcgiges Studio mit herrlicher Aussicht, Himmelbett, Wohn-\/Essecke und K\u00fcchenzeile. Sitzplatz direkt vor dem Apartment im Garten.","twitter:image":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg"},"aioseo_meta_data":{"post_id":"3867","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-01 09:04:35","updated":"2026-07-15 12:31:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/belfiore-italia.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/belfiore-italia.com\/de\/accommodation\/\" title=\"Unterkunftsarten\">Unterkunftsarten<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/belfiore-italia.com\/de\/accommodation-category\/en-suite-de\/\" title=\"En suite\">En suite<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMimosa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/belfiore-italia.com\/de\/"},{"label":"Unterkunftsarten","link":"https:\/\/belfiore-italia.com\/de\/accommodation\/"},{"label":"En suite","link":"https:\/\/belfiore-italia.com\/de\/accommodation-category\/en-suite-de\/"},{"label":"Mimosa","link":"https:\/\/belfiore-italia.com\/de\/accommodation\/mimosa\/"}],"_links":{"self":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type\/3867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type"}],"about":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/types\/mphb_room_type"}],"replies":[{"embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/comments?post=3867"}],"version-history":[{"count":33,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type\/3867\/revisions"}],"predecessor-version":[{"id":7720,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type\/3867\/revisions\/7720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/media\/494"}],"wp:attachment":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/media?parent=3867"}],"wp:term":[{"taxonomy":"mphb_room_type_category","embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type_category?post=3867"},{"taxonomy":"mphb_room_type_tag","embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type_tag?post=3867"},{"taxonomy":"mphb_room_type_facility","embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/mphb_room_type_facility?post=3867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}