{"id":3821,"date":"2023-04-10T20:27:59","date_gmt":"2023-04-10T18:27:59","guid":{"rendered":"https:\/\/belfiore-italia.com\/bedingungen\/"},"modified":"2026-06-10T11:59:58","modified_gmt":"2026-06-10T09:59:58","slug":"bedingungen","status":"publish","type":"page","link":"https:\/\/belfiore-italia.com\/de\/bedingungen\/","title":{"rendered":"Gesch\u00e4ftsbedingungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3821\" class=\"elementor elementor-3821 elementor-2438\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b84818c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b84818c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9454ba5\" data-id=\"9454ba5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50ec908 elementor-widget elementor-widget-menu-anchor\" data-id=\"50ec908\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"location\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ebdae0 elementor-widget elementor-widget-spacer\" data-id=\"6ebdae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18a9766 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18a9766\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-19724b2\" data-id=\"19724b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fec9d1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8fec9d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bedingungen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b06cd8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1b06cd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"list-style-type: none;\"><ul><li><strong>Hochsaison:<\/strong><br \/>11.07.2026 \u2013 28.08.2026<\/li><li><strong>Nebensaison:<\/strong><br \/>01.04.2026 \u2013 10.07.2026<br \/>29.08.2026 \u2013 03.10.2026<\/li><li>Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.<\/li><li>Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.<\/li><li>Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor anreise f\u00e4llig.<\/li><li>Kaution \u20ac200.<\/li><li>Wir empfehlen unseren g\u00e4sten den abschluss einer reiser\u00fccktrittsversicherung.<\/li><li>Die preise sind pro woche und beinhalten bettw\u00e4sche, w\u00f6chentlich gewechselt, und handt\u00fccher, 2x pro woche gewechselt.<\/li><li>Endreinigungskosten sind obligatorisch und abh\u00e4ngig von der gr\u00f6sse der unterkunft: \u20ac50 &#8211; \u20ac80.<\/li><li>Zus\u00e4tzliche reinigung sowie extra wechsel von bettw\u00e4sche un handt\u00fcchern gegen aufpreis m\u00f6glich.<\/li><li>Kostenlose benutzung der waschmaschine und waschmittel.<\/li><li><strong>Kostenloses WLAN internet.<\/strong>\u00a0<\/li><li>Bringen sie ihre eigenen badet\u00fccher mit oder leihen sie eines f\u00fcr \u20ac5.<\/li><li><strong>T\u00e4glich frisches brot und cappuccino.<\/strong><\/li><li>Fr\u00fchst\u00fcck ist in der nebensaison ausschliesslich auf anfrage erh\u00e4ltlich.<\/li><li>Zusatzbett wenn m\u00f6glich (+) \u20ac110 pro woche.<\/li><li>Fragen Sie nach zus\u00e4tzlichen heizkostenzuschlag in den wintermonaten (je nach unterkunft).<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-110c917 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"110c917\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c3fb58d\" data-id=\"c3fb58d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adca62b elementor-view-default elementor-position-top elementor-widget elementor-widget-themo-header\" data-id=\"adca62b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"themo-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"th-header-wrap\">\n        <div class=\"elementor-icon-box-wrapper \">\n                            <div class=\"elementor-icon-box-content\">\n                    <h1 class=\"elementor-icon-box-title\">\n                                            <\/h1>\n                                        <p class=\"elementor-icon-box-description\">Bitte nehmen sie eine reservierung \u00fcber unser kontaktformular vor. Unser Team spricht Deutsch, Niederl\u00e4ndisch und Englisch. Sie k\u00f6nnen uns bei allen fragen per telefon, e-mail oder whatsapp erreichen.  <\/p>\n\n                                            <div class=\"th-btn-wrap\">\n                                                            <a class=\"btn-1 btn th-btn btn-standard-primary\" href=\"\/contact-us\">\n                                                                            Kontakt.                                                                    <\/a>\n                            \n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-df87ad5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df87ad5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-286304a\" data-id=\"286304a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0947bdf elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0947bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Folgen Sie uns auf Social Media:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6de9390\" data-id=\"6de9390\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f854ed e-grid-align-left elementor-widget__width-initial elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"1f854ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-9a6162b\" href=\"https:\/\/wa.me\/393484627954\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-3bb8304\" href=\"https:\/\/www.facebook.com\/525995467458539\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-eecd03e\" href=\"https:\/\/www.instagram.com\/borgo_belfiore\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026 Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026 Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr. Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor &hellip; <a href=\"https:\/\/belfiore-italia.com\/de\/bedingungen\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3821","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/belfiore-italia.com\/de\/bedingungen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Borgo Belfiore - Family vacation in Le Marche\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Gesch\u00e4ftsbedingungen - Borgo Belfiore\" \/>\n\t\t<meta property=\"og:description\" content=\"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/belfiore-italia.com\/de\/bedingungen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"85\" \/>\n\t\t<meta property=\"og:image:height\" content=\"80\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-10T18:27:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-10T09:59:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/525995467458539\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@borgobelfiore\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Gesch\u00e4ftsbedingungen - Borgo Belfiore\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@borgobelfiore\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#listItem\",\"name\":\"Gesch\\u00e4ftsbedingungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#listItem\",\"position\":2,\"name\":\"Gesch\\u00e4ftsbedingungen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#organization\",\"name\":\"Borgo Belfiore\",\"description\":\"Family vacation in Le Marche\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/\",\"telephone\":\"+393484627974\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_belfioriO1-2.jpg\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#organizationLogo\",\"width\":85,\"height\":80,\"caption\":\"Agriturismo Borgo Belfiore logo\"},\"image\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/525995467458539\",\"https:\\\/\\\/twitter.com\\\/borgobelfiore\",\"https:\\\/\\\/www.instagram.com\\\/borgo_belfiore\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#webpage\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/\",\"name\":\"Gesch\\u00e4ftsbedingungen - Borgo Belfiore\",\"description\":\"Bedingungen Hochsaison:11.07.2026 \\u2013 28.08.2026Nebensaison:01.04.2026 \\u2013 10.07.202629.08.2026 \\u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/bedingungen\\\/#breadcrumblist\"},\"datePublished\":\"2023-04-10T20:27:59+02:00\",\"dateModified\":\"2026-06-10T11:59:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/\",\"name\":\"Borgo Belfiore\",\"description\":\"Family vacation in Le Marche\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/belfiore-italia.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Gesch\u00e4ftsbedingungen - Borgo Belfiore","description":"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor","canonical_url":"https:\/\/belfiore-italia.com\/de\/bedingungen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/belfiore-italia.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#listItem","name":"Gesch\u00e4ftsbedingungen"}},{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#listItem","position":2,"name":"Gesch\u00e4ftsbedingungen","previousItem":{"@type":"ListItem","@id":"https:\/\/belfiore-italia.com\/de\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/belfiore-italia.com\/de\/#organization","name":"Borgo Belfiore","description":"Family vacation in Le Marche","url":"https:\/\/belfiore-italia.com\/de\/","telephone":"+393484627974","logo":{"@type":"ImageObject","url":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg","@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#organizationLogo","width":85,"height":80,"caption":"Agriturismo Borgo Belfiore logo"},"image":{"@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/525995467458539","https:\/\/twitter.com\/borgobelfiore","https:\/\/www.instagram.com\/borgo_belfiore\/"]},{"@type":"WebPage","@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#webpage","url":"https:\/\/belfiore-italia.com\/de\/bedingungen\/","name":"Gesch\u00e4ftsbedingungen - Borgo Belfiore","description":"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/belfiore-italia.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/belfiore-italia.com\/de\/bedingungen\/#breadcrumblist"},"datePublished":"2023-04-10T20:27:59+02:00","dateModified":"2026-06-10T11:59:58+02:00"},{"@type":"WebSite","@id":"https:\/\/belfiore-italia.com\/de\/#website","url":"https:\/\/belfiore-italia.com\/de\/","name":"Borgo Belfiore","description":"Family vacation in Le Marche","inLanguage":"de-DE","publisher":{"@id":"https:\/\/belfiore-italia.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Borgo Belfiore - Family vacation in Le Marche","og:type":"article","og:title":"Gesch\u00e4ftsbedingungen - Borgo Belfiore","og:description":"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor","og:url":"https:\/\/belfiore-italia.com\/de\/bedingungen\/","og:image":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg","og:image:secure_url":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg","og:image:width":85,"og:image:height":80,"article:published_time":"2023-04-10T18:27:59+00:00","article:modified_time":"2026-06-10T09:59:58+00:00","article:publisher":"https:\/\/www.facebook.com\/525995467458539","twitter:card":"summary_large_image","twitter:site":"@borgobelfiore","twitter:title":"Gesch\u00e4ftsbedingungen - Borgo Belfiore","twitter:description":"Bedingungen Hochsaison:11.07.2026 \u2013 28.08.2026Nebensaison:01.04.2026 \u2013 10.07.202629.08.2026 \u2013 03.10.2026Hochsaison mindestens 3 tage, anreise an jedem tag m\u00f6glich, anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Nebensaison mindestens 3 tage, anreise an jedem tag m\u00f6glich,anreise ab 16:00 uhr, Abreise vor 10:00 uhr.Wir best\u00e4tigen ihre buchung nach erhalt von 50% anzahlung der rechnung. Der restbetrag ist 6 wochen vor","twitter:creator":"@borgobelfiore","twitter:image":"https:\/\/belfiore-italia.com\/wp-content\/uploads\/2022\/02\/logo_belfioriO1-2.jpg"},"aioseo_meta_data":{"post_id":"3821","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-31 07:29:32","updated":"2026-06-10 10:00:17","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/belfiore-italia.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGesch\u00e4ftsbedingungen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/belfiore-italia.com\/de\/"},{"label":"Gesch\u00e4ftsbedingungen","link":"https:\/\/belfiore-italia.com\/de\/bedingungen\/"}],"_links":{"self":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/pages\/3821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/comments?post=3821"}],"version-history":[{"count":29,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/pages\/3821\/revisions"}],"predecessor-version":[{"id":8755,"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/pages\/3821\/revisions\/8755"}],"wp:attachment":[{"href":"https:\/\/belfiore-italia.com\/de\/wp-json\/wp\/v2\/media?parent=3821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}